{"id":11336,"date":"2026-06-12T14:24:12","date_gmt":"2026-06-12T08:54:12","guid":{"rendered":"https:\/\/tigrisvalley.com\/?page_id=11336"},"modified":"2026-07-21T15:27:39","modified_gmt":"2026-07-21T09:57:39","slug":"detox-retreat-india-for-europeans","status":"publish","type":"page","link":"https:\/\/tigrisvalley.com\/de\/detox-retreat-india-for-europeans\/","title":{"rendered":"Detox-Urlaub in Indien f\u00fcr Europ\u00e4er"},"content":{"rendered":"<section class=\"bde-section-11336-100 bde-section\">\n  \n  \n\t\n\n\n\n<div class=\"section-container\"><div class=\"bde-columns-11336-101 bde-columns\"><div class=\"bde-column-11336-102 bde-column\" data-entrance=\"slideUp\">\n  \n  \n\t\n\n\n\n<h1 class=\"bde-heading-11336-103 bde-heading\">\nDas Detox-Retreat in Indien f\u00fcr Europ\u00e4er, das mehr bietet als eine einfache Saftkur\n<\/h1><div class=\"bde-text-11336-104 bde-text\">\nDu hast es schon mit \u201eClean Eating\u201c versucht. Du hast die Wochenend-Entgiftung gemacht. Du hast auf Alkohol, Gluten und Zucker verzichtet. Und doch f\u00fchlst du dich innerlich immer noch schwer, tr\u00e4ge und unausgeglichen. Das liegt daran, dass die meisten Entgiftungsprogramme nur an der Oberfl\u00e4che kratzen \u2013 und dein K\u00f6rper Giftstoffe viel tiefer im K\u00f6rper speichert.<br>Das moderne Leben in Europa ist eine der giftigsten Umgebungen, mit denen Ihr K\u00f6rper je zurechtkommen musste \u2013 verarbeitete Lebensmittel, Luftverschmutzung, chronischer Stress, R\u00fcckst\u00e4nde von Medikamenten und die unerbittliche Reiz\u00fcberflutung in der Stadt, die nie ganz nachl\u00e4sst.<br>Oberfl\u00e4chliche Entgiftungskuren reichen nicht aus, um die Stoffe zu beseitigen, die sich in Ihrem Gewebe, Ihrer Leber und Ihrer Darmschleimhaut angesammelt haben.<br>Im Tigris Valley, Keralas medizinisch betreuten Entgiftungszentrum, gehen wir bis auf die zellul\u00e4re Ebene.\n<\/div><div class=\"bde-button-11336-105 bde-button\">\n        \n    \n    \n    \n    \n            \n                    \n            \n            \n\n    \n    \n    \n    \n    \n    <a class=\"breakdance-link button-atom button-atom--primary bde-button__button\" href=\"\/de\/contact-us\/\" target=\"_self\" data-type=\"url\"  >\n\n    \n        <span class=\"button-atom__text\">jetzt buchen<\/span>\n\n        \n        \n                <\/a>\n\n    \n\n\n<\/div>\n<\/div><div class=\"bde-column-11336-106 bde-column\">\n  \n  \n\t\n\n\n\n<div class=\"bde-image-11336-107 bde-image\" data-entrance=\"fade\">\n<figure class=\"breakdance-image breakdance-image--10961\">\n\t<div class=\"breakdance-image-container\">\n\t\t<div class=\"breakdance-image-clip\"><img loading=\"lazy\" decoding=\"async\" class=\"breakdance-image-object\" src=\"https:\/\/tigrisvalley.com\/wp-content\/uploads\/2026\/05\/ChatGPT-Image-May-26-2026-04_14_12-PM-1.webp\" width=\"1536\" height=\"1024\" srcset=\"https:\/\/tigrisvalley.com\/wp-content\/uploads\/2026\/05\/ChatGPT-Image-May-26-2026-04_14_12-PM-1.webp 1536w, https:\/\/tigrisvalley.com\/wp-content\/uploads\/2026\/05\/ChatGPT-Image-May-26-2026-04_14_12-PM-1-300x200.webp 300w, https:\/\/tigrisvalley.com\/wp-content\/uploads\/2026\/05\/ChatGPT-Image-May-26-2026-04_14_12-PM-1-1024x683.webp 1024w, https:\/\/tigrisvalley.com\/wp-content\/uploads\/2026\/05\/ChatGPT-Image-May-26-2026-04_14_12-PM-1-768x512.webp 768w, https:\/\/tigrisvalley.com\/wp-content\/uploads\/2026\/05\/ChatGPT-Image-May-26-2026-04_14_12-PM-1-18x12.webp 18w\" sizes=\"auto, (max-width: 1536px) 100vw, 1536px\"><\/div>\n\t<\/div><\/figure>\n\n<\/div>\n<\/div><\/div><div class=\"bde-stats-grid-11336-236 bde-stats-grid\">\n  <div class='bde-stats-grid_item'>\n          \n    \n            <div class=\"bde-stats-grid_icon breakdance-icon-atom\" >\n    \n                    <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 512 512\"><!--! Font Awesome Free 6.5.1 by @fontawesome - https:\/\/fontawesome.com License - https:\/\/fontawesome.com\/license\/free (Icons: CC BY 4.0, Fonts: SIL OFL 1.1, Code: MIT License) Copyright 2023 Fonticons, Inc. --><path d=\"M211 7.3C205 1 196-1.4 187.6 .8s-14.9 8.9-17.1 17.3L154.7 80.6l-62-17.5c-8.4-2.4-17.4 0-23.5 6.1s-8.5 15.1-6.1 23.5l17.5 62L18.1 170.6c-8.4 2.1-15 8.7-17.3 17.1S1 205 7.3 211l46.2 45L7.3 301C1 307-1.4 316 .8 324.4s8.9 14.9 17.3 17.1l62.5 15.8-17.5 62c-2.4 8.4 0 17.4 6.1 23.5s15.1 8.5 23.5 6.1l62-17.5 15.8 62.5c2.1 8.4 8.7 15 17.1 17.3s17.3-.2 23.4-6.4l45-46.2 45 46.2c6.1 6.2 15 8.7 23.4 6.4s14.9-8.9 17.1-17.3l15.8-62.5 62 17.5c8.4 2.4 17.4 0 23.5-6.1s8.5-15.1 6.1-23.5l-17.5-62 62.5-15.8c8.4-2.1 15-8.7 17.3-17.1s-.2-17.4-6.4-23.4l-46.2-45 46.2-45c6.2-6.1 8.7-15 6.4-23.4s-8.9-14.9-17.3-17.1l-62.5-15.8 17.5-62c2.4-8.4 0-17.4-6.1-23.5s-15.1-8.5-23.5-6.1l-62 17.5L341.4 18.1c-2.1-8.4-8.7-15-17.1-17.3S307 1 301 7.3L256 53.5 211 7.3z\"\/><\/svg>\n        \n        \n        \n            <\/div>\n    \n\n        <h3 class='bde-stats-grid_number' >\n      \n    <\/h3>\n    <p class='bde-stats-grid_text' >\n      AYUSH-zertifiziert\n    <\/p>\n  <\/div>\n  <div class='bde-stats-grid_item'>\n          \n    \n            <div class=\"bde-stats-grid_icon breakdance-icon-atom\" >\n    \n                    <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"icon-earth\" viewbox=\"0 0 32 32\">\n<path d=\"M16 0c-8.837 0-16 7.163-16 16s7.163 16 16 16 16-7.163 16-16-7.163-16-16-16zM16 30c-1.967 0-3.84-0.407-5.538-1.139l7.286-8.197c0.163-0.183 0.253-0.419 0.253-0.664v-3c0-0.552-0.448-1-1-1-3.531 0-7.256-3.671-7.293-3.707-0.188-0.188-0.442-0.293-0.707-0.293h-4c-0.552 0-1 0.448-1 1v6c0 0.379 0.214 0.725 0.553 0.894l3.447 1.724v5.871c-3.627-2.53-6-6.732-6-11.489 0-2.147 0.484-4.181 1.348-6h3.652c0.265 0 0.52-0.105 0.707-0.293l4-4c0.188-0.188 0.293-0.442 0.293-0.707v-2.419c1.268-0.377 2.61-0.581 4-0.581 2.2 0 4.281 0.508 6.134 1.412-0.13 0.109-0.256 0.224-0.376 0.345-1.133 1.133-1.757 2.64-1.757 4.243s0.624 3.109 1.757 4.243c1.139 1.139 2.663 1.758 4.239 1.758 0.099 0 0.198-0.002 0.297-0.007 0.432 1.619 1.211 5.833-0.263 11.635-0.014 0.055-0.022 0.109-0.026 0.163-2.541 2.596-6.084 4.208-10.004 4.208z\"\/>\n<\/svg>\n        \n        \n        \n            <\/div>\n    \n\n        <h3 class='bde-stats-grid_number' >\n      \n    <\/h3>\n    <p class='bde-stats-grid_text' >\n      UNESCO-anerkannt\n    <\/p>\n  <\/div>\n  <div class='bde-stats-grid_item'>\n          \n    \n            <div class=\"bde-stats-grid_icon breakdance-icon-atom\" >\n    \n                    <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 496 512\"><!-- Font Awesome Free 5.15.1 by @fontawesome - https:\/\/fontawesome.com License - https:\/\/fontawesome.com\/license\/free (Icons: CC BY 4.0, Fonts: SIL OFL 1.1, Code: MIT License) --><path d=\"M248 8C111.03 8 0 119.03 0 256s111.03 248 248 248 248-111.03 248-248S384.97 8 248 8zm160 215.5v6.93c0 5.87-3.32 11.24-8.57 13.86l-15.39 7.7a15.485 15.485 0 0 1-15.53-.97l-18.21-12.14a15.52 15.52 0 0 0-13.5-1.81l-2.65.88c-9.7 3.23-13.66 14.79-7.99 23.3l13.24 19.86c2.87 4.31 7.71 6.9 12.89 6.9h8.21c8.56 0 15.5 6.94 15.5 15.5v11.34c0 3.35-1.09 6.62-3.1 9.3l-18.74 24.98c-1.42 1.9-2.39 4.1-2.83 6.43l-4.3 22.83c-.62 3.29-2.29 6.29-4.76 8.56a159.608 159.608 0 0 0-25 29.16l-13.03 19.55a27.756 27.756 0 0 1-23.09 12.36c-10.51 0-20.12-5.94-24.82-15.34a78.902 78.902 0 0 1-8.33-35.29V367.5c0-8.56-6.94-15.5-15.5-15.5h-25.88c-14.49 0-28.38-5.76-38.63-16a54.659 54.659 0 0 1-16-38.63v-14.06c0-17.19 8.1-33.38 21.85-43.7l27.58-20.69a54.663 54.663 0 0 1 32.78-10.93h.89c8.48 0 16.85 1.97 24.43 5.77l14.72 7.36c3.68 1.84 7.93 2.14 11.83.84l47.31-15.77c6.33-2.11 10.6-8.03 10.6-14.7 0-8.56-6.94-15.5-15.5-15.5h-10.09c-4.11 0-8.05-1.63-10.96-4.54l-6.92-6.92a15.493 15.493 0 0 0-10.96-4.54H199.5c-8.56 0-15.5-6.94-15.5-15.5v-4.4c0-7.11 4.84-13.31 11.74-15.04l14.45-3.61c3.74-.94 7-3.23 9.14-6.44l8.08-12.11c2.87-4.31 7.71-6.9 12.89-6.9h24.21c8.56 0 15.5-6.94 15.5-15.5v-21.7C359.23 71.63 422.86 131.02 441.93 208H423.5c-8.56 0-15.5 6.94-15.5 15.5z\"\/><\/svg>\n        \n        \n        \n            <\/div>\n    \n\n        <h3 class='bde-stats-grid_number' >\n      \n    <\/h3>\n    <p class='bde-stats-grid_text' >\n      ISO-akkreditiert\n    <\/p>\n  <\/div>\n  <div class='bde-stats-grid_item'>\n          \n    \n            <div class=\"bde-stats-grid_icon breakdance-icon-atom\" >\n    \n                    <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 576 512\"><!--! Font Awesome Free 6.5.1 by @fontawesome - https:\/\/fontawesome.com License - https:\/\/fontawesome.com\/license\/free (Icons: CC BY 4.0, Fonts: SIL OFL 1.1, Code: MIT License) Copyright 2023 Fonticons, Inc. --><path d=\"M48 0C21.5 0 0 21.5 0 48V256H144c8.8 0 16 7.2 16 16s-7.2 16-16 16H0v64H144c8.8 0 16 7.2 16 16s-7.2 16-16 16H0v80c0 26.5 21.5 48 48 48H265.9c-6.3-10.2-9.9-22.2-9.9-35.1c0-46.9 25.8-87.8 64-109.2V271.8 48c0-26.5-21.5-48-48-48H48zM152 64h16c8.8 0 16 7.2 16 16v24h24c8.8 0 16 7.2 16 16v16c0 8.8-7.2 16-16 16H184v24c0 8.8-7.2 16-16 16H152c-8.8 0-16-7.2-16-16V152H112c-8.8 0-16-7.2-16-16V120c0-8.8 7.2-16 16-16h24V80c0-8.8 7.2-16 16-16zM512 272a80 80 0 1 0 -160 0 80 80 0 1 0 160 0zM288 477.1c0 19.3 15.6 34.9 34.9 34.9H541.1c19.3 0 34.9-15.6 34.9-34.9c0-51.4-41.7-93.1-93.1-93.1H381.1c-51.4 0-93.1 41.7-93.1 93.1z\"\/><\/svg>\n        \n        \n        \n            <\/div>\n    \n\n        <h3 class='bde-stats-grid_number' >\n      \n    <\/h3>\n    <p class='bde-stats-grid_text' >\n      Internationales Patientenzentrum\n    <\/p>\n  <\/div>\n  <div class='bde-stats-grid_item'>\n          \n    \n            <div class=\"bde-stats-grid_icon breakdance-icon-atom\" >\n    \n                    <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 448 512\"><!--! Font Awesome Free 6.5.1 by @fontawesome - https:\/\/fontawesome.com License - https:\/\/fontawesome.com\/license\/free (Icons: CC BY 4.0, Fonts: SIL OFL 1.1, Code: MIT License) Copyright 2023 Fonticons, Inc. --><path d=\"M224 256A128 128 0 1 0 224 0a128 128 0 1 0 0 256zm-96 55.2C54 332.9 0 401.3 0 482.3C0 498.7 13.3 512 29.7 512H418.3c16.4 0 29.7-13.3 29.7-29.7c0-81-54-149.4-128-171.1V362c27.6 7.1 48 32.2 48 62v40c0 8.8-7.2 16-16 16H336c-8.8 0-16-7.2-16-16s7.2-16 16-16V424c0-17.7-14.3-32-32-32s-32 14.3-32 32v24c8.8 0 16 7.2 16 16s-7.2 16-16 16H256c-8.8 0-16-7.2-16-16V424c0-29.8 20.4-54.9 48-62V304.9c-6-.6-12.1-.9-18.3-.9H178.3c-6.2 0-12.3 .3-18.3 .9v65.4c23.1 6.9 40 28.3 40 53.7c0 30.9-25.1 56-56 56s-56-25.1-56-56c0-25.4 16.9-46.8 40-53.7V311.2zM144 448a24 24 0 1 0 0-48 24 24 0 1 0 0 48z\"\/><\/svg>\n        \n        \n        \n            <\/div>\n    \n\n        <h3 class='bde-stats-grid_number' >\n     20+ \n    <\/h3>\n    <p class='bde-stats-grid_text' >\n      Fach\u00e4rztinnen und Fach\u00e4rzte\n    <\/p>\n  <\/div>\n  <div class='bde-stats-grid_item'>\n          \n    \n            <div class=\"bde-stats-grid_icon breakdance-icon-atom\" >\n    \n                    <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"icon-happy\" viewbox=\"0 0 32 32\">\n<path d=\"M16 32c8.837 0 16-7.163 16-16s-7.163-16-16-16-16 7.163-16 16 7.163 16 16 16zM16 3c7.18 0 13 5.82 13 13s-5.82 13-13 13-13-5.82-13-13 5.82-13 13-13zM16 18.711c3.623 0 7.070-0.963 10-2.654-0.455 5.576-4.785 9.942-10 9.942s-9.544-4.371-10-9.947c2.93 1.691 6.377 2.658 10 2.658zM8 11c0-1.657 0.895-3 2-3s2 1.343 2 3c0 1.657-0.895 3-2 3s-2-1.343-2-3zM20 11c0-1.657 0.895-3 2-3s2 1.343 2 3c0 1.657-0.895 3-2 3s-2-1.343-2-3z\"\/>\n<\/svg>\n        \n        \n        \n            <\/div>\n    \n\n        <h3 class='bde-stats-grid_number' >\n     5000+\n    <\/h3>\n    <p class='bde-stats-grid_text' >\n      Behandelte Patienten\n    <\/p>\n  <\/div>\n\n<\/div><\/div>\n<\/section><section class=\"bde-section-11336-111 bde-section\">\n  \n  \n\t\n\n\n\n<div class=\"section-container\"><h2 class=\"bde-heading-11336-114 bde-heading\" data-entrance=\"slideUp\">\nWarum Europ\u00e4er speziell zum Entgiften und zur Entschlackung nach Indien reisen<br>\n<\/h2><div class=\"bde-columns-11336-115 bde-columns\"><div class=\"bde-column-11336-116 bde-column\">\n  \n  \n\t\n\n\n\n<div class=\"bde-image-11336-316 bde-image\">\n<figure class=\"breakdance-image breakdance-image--10969\">\n\t<div class=\"breakdance-image-container\">\n\t\t<div class=\"breakdance-image-clip\"><img loading=\"lazy\" decoding=\"async\" class=\"breakdance-image-object\" src=\"https:\/\/tigrisvalley.com\/wp-content\/uploads\/2026\/05\/ChatGPT-Image-May-26-2026-04_16_29-PM.webp\" width=\"1303\" height=\"977\" srcset=\"https:\/\/tigrisvalley.com\/wp-content\/uploads\/2026\/05\/ChatGPT-Image-May-26-2026-04_16_29-PM.webp 1303w, https:\/\/tigrisvalley.com\/wp-content\/uploads\/2026\/05\/ChatGPT-Image-May-26-2026-04_16_29-PM-300x225.webp 300w, https:\/\/tigrisvalley.com\/wp-content\/uploads\/2026\/05\/ChatGPT-Image-May-26-2026-04_16_29-PM-1024x768.webp 1024w, https:\/\/tigrisvalley.com\/wp-content\/uploads\/2026\/05\/ChatGPT-Image-May-26-2026-04_16_29-PM-768x576.webp 768w, https:\/\/tigrisvalley.com\/wp-content\/uploads\/2026\/05\/ChatGPT-Image-May-26-2026-04_16_29-PM-16x12.webp 16w\" sizes=\"auto, (max-width: 1303px) 100vw, 1303px\"><\/div>\n\t<\/div><\/figure>\n\n<\/div>\n<\/div><div class=\"bde-column-11336-117 bde-column\" data-entrance=\"slideUp\">\n  \n  \n\t\n\n\n\n<div class=\"bde-text-11336-118 bde-text\">\nDie europ\u00e4ische Wellnesskultur ist vielf\u00e4ltig. Deutschland hat seine Kurtradition, Skandinavien seine Saunen, Gro\u00dfbritannien seine Landgasth\u00f6fe. Und doch machen sich Jahr f\u00fcr Jahr Tausende von Europ\u00e4ern auf den langen Weg nach Kerala in Indien \u2013 denn was hier geschieht, l\u00e4sst sich nirgendwo in Europa nachahmen.<br>Kerala ist der einzige Ort auf der Welt, an dem Panchakarma \u2013 das klassische f\u00fcnfstufige System der Zellreinigung im Ayurveda \u2013 in seiner authentischen, unverf\u00e4lschten Form praktiziert wird, und zwar von \u00c4rzten, die es als vollwertige medizinische Disziplin und nicht als Wellness-Anwendung erlernt haben. Die in den Behandlungen verwendeten Heilpflanzen wachsen in den W\u00e4ldern Keralas. Das bei den \u00d6lbehandlungen verwendete Ghee wird in unserer hauseigenen ayurvedischen Apotheke hergestellt. Die Kashayam (Kr\u00e4utersud), die jeden Morgen serviert werden, werden frisch f\u00fcr die spezifische Konstitution und die toxische Belastung jedes einzelnen Patienten zusammengestellt.<br>Das ist kein Wellness-Tourismus. Das ist eine klinische Entgiftung \u2013 eine, die messbare, dokumentierte und dauerhafte Ver\u00e4nderungen im K\u00f6rper bewirkt.<br>Das \u201eTigris Valley\u201c, ein Entgiftungszentrum in Indien f\u00fcr Europ\u00e4er, st\u00fctzt sich auf drei Jahrzehnte Erfahrung des Gr\u00fcnders und Arztes, ein Team von \u00fcber 20 Spezialisten aus acht verschiedenen Heilungssystemen sowie eine medizinische Philosophie, die Toxizit\u00e4t nicht als blo\u00dfe Unannehmlichkeit betrachtet, sondern als Grundursache f\u00fcr praktisch jede chronische Erkrankung, mit der Europ\u00e4er zu uns kommen.\n<\/div><div class=\"bde-button-11336-119 bde-button\">\n        \n    \n    \n    \n    \n            \n                    \n            \n            \n\n    \n    \n    \n    \n    \n    <a class=\"breakdance-link button-atom button-atom--primary bde-button__button\" href=\"\/de\/contact-us\/\" target=\"_self\" data-type=\"url\"  >\n\n    \n        <span class=\"button-atom__text\">Konsultation buchen<\/span>\n\n        \n        \n                <\/a>\n\n    \n\n\n<\/div>\n<\/div><\/div><\/div>\n<\/section><section class=\"bde-section-11336-121 bde-section\">\n  \n  \n\t\n\n\n\n<div class=\"section-container\"><h2 class=\"bde-heading-11336-122 bde-heading\" data-entrance=\"slideUp\">\nWas das \u201eTigris Valley Detox &amp; Cleanse\u201c-Programm tats\u00e4chlich mit Ihrem K\u00f6rper macht\n<\/h2><div class=\"bde-text-11336-176 bde-text\">\nDer K\u00f6rper sammelt \u00fcber Jahre hinweg \u2013 manchmal sogar \u00fcber Jahrzehnte \u2013 toxische Belastungen an. Umweltgifte, Pestizidr\u00fcckst\u00e4nde in Lebensmitteln, pharmazeutische Verbindungen, Schwermetalle aus beruflicher oder st\u00e4dtischer Exposition sowie die durch chronischen Stress entstehenden Stoffwechselabf\u00e4lle lagern sich im Gewebe ab, st\u00f6ren die Integrit\u00e4t des Darms und bilden das, was die ayurvedische Medizin als \u201eAma\u201c bezeichnet \u2013 die klebrigen, unverdauten R\u00fcckst\u00e4nde, die die nat\u00fcrlichen Ausscheidungskan\u00e4le des K\u00f6rpers verstopfen.<br>Unser Entgiftungs- und Reinigungsprogramm gliedert sich in drei klar voneinander abgegrenzte, medizinisch aufeinander abgestimmte Phasen. Jede Phase baut auf der vorherigen auf. Das \u00dcberspringen einer dieser Phasen \u2013 wie es bei den meisten kommerziellen Entgiftungsprogrammen der Fall ist \u2013 schr\u00e4nkt die Tiefe und Nachhaltigkeit der Ergebnisse ein.<br>\n<\/div><div class=\"bde-columns-11336-123 bde-columns\" data-entrance=\"slideUp\"><div class=\"bde-column-11336-255 bde-column\">\n  \n  \n\t\n\n\n\n<h6 class=\"bde-heading-11336-256 bde-heading\">\nPhase 1 \u2013 Vorbereitung: Festgefahrenes l\u00f6sen\n<\/h6><div class=\"bde-text-11336-257 bde-text\">\nBevor eine Tiefenreinigung stattfinden kann, m\u00fcssen zun\u00e4chst die im Gewebe abgelagerten Giftstoffe mobilisiert und zur Ausscheidung in den Verdauungstrakt geleitet werden. Dies ist die Phase, die in den meisten europ\u00e4ischen Entgiftungsprogrammen v\u00f6llig au\u00dfer Acht gelassen wird.<br><br><b>Innere Snehana (\u00d6lbehandlung): <\/b>Medizinisches Ghee wird \u00fcber mehrere Tage hinweg in schrittweise steigenden Dosen oral eingenommen. Spezielle Kr\u00e4uter-Ghee-Pr\u00e4parate \u2013 die auf der Grundlage Ihres diagnostischen Profils ausgew\u00e4hlt werden \u2013 dringen tief in die Gewebeschichten ein, l\u00f6sen fettl\u00f6sliche Giftstoffe (einschlie\u00dflich Umweltchemikalien und Schwermetalle) auf und wandern in Richtung Darm<br><b>\u00c4u\u00dferes Abhyanga:<\/b> Eine synchronisierte Ganzk\u00f6rpermassage mit warmen medizinischen \u00d6len, die t\u00e4glich von zwei Therapeuten gleichzeitig durchgef\u00fchrt wird, um Giftstoffe aus Muskeln, Gelenken und dem Lymphsystem zu mobilisieren<br><b>Swedana (Dampftherapie):<\/b> Gezielte Kr\u00e4uter-Dampftherapie zur \u00d6ffnung der Meridiane, zur F\u00f6rderung des Lymphabflusses und zur Vorbereitung des Gewebes auf eine tiefere Reinigung<br><b>Umstellung der Ern\u00e4hrung:<\/b> Ihre Ern\u00e4hrung wird schrittweise vereinfacht \u2013 zun\u00e4chst auf leicht verdauliche Vollwertkost, dann auf Manda (d\u00fcnner Reisbrei) \u2013, sodass das Verdauungssystem seine Energie auf die Entgiftung statt auf die Verarbeitung komplexer Nahrungsmittel konzentrieren kann\n<\/div>\n<\/div><div class=\"bde-column-11336-150 bde-column\">\n  \n  \n\t\n\n\n\n<h6 class=\"bde-heading-11336-151 bde-heading\">\nPhase 2 \u2013 Entschlackung: Klassische Panchakarma-Behandlungsabl\u00e4ufe\n<\/h6><div class=\"bde-text-11336-153 bde-text\">\nDas ist der entscheidende Unterschied zwischen dem Tigris Valley und allen anderen Entgiftungszentren in Europa oder anderswo. Das klassische Panchakarma \u2013 die f\u00fcnf Reinigungsverfahren des Ayurveda \u2013 wird erst dann durchgef\u00fchrt, wenn Ihr K\u00f6rper ausreichend vorbereitet ist und Ihr Arzt die f\u00fcr Ihre Konstitution geeignete Abfolge und Intensit\u00e4t festgelegt hat.<br><br><b>Virechana (Therapeutische Purgation):<\/b> Eine pr\u00e4zise abgestimmte Kr\u00e4uterkur, die den D\u00fcnndarm, die Gallenblase und die Leber von angesammelter Galle, Entz\u00fcndungsstoffen und Stoffwechselabf\u00e4llen befreit. Besonders wirksam f\u00fcr G\u00e4ste aus Europa, die unter Hautproblemen, einer durch Alkohol- oder Medikamentenkonsum verursachten Leberbelastung sowie chronischen Entz\u00fcndungserkrankungen leiden<br><b>Basti (medizinische Einlauftherapie): <\/b>Basti gilt als die wirksamste aller Panchakarma-Behandlungen. Dabei wird eine Abfolge von medizinischen \u00d6len und Kr\u00e4utersud rektal verabreicht, um den Dickdarm zu reinigen, die f\u00fcr die Ausscheidung verantwortliche Vata-Energie (Nervensystem und Bewegung) wieder ins Gleichgewicht zu bringen und die Integrit\u00e4t des Darmmikrobioms wiederherzustellen<br><b>Nasya (Nasentherapie): <\/b>Medizinische Kr\u00e4uter\u00f6le, die \u00fcber die Nasenwege verabreicht werden, um angesammelte Giftstoffe aus dem Kopf, den Nasennebenh\u00f6hlen und den Nervenbahnen zu entfernen \u2013 besonders geeignet f\u00fcr europ\u00e4ische G\u00e4ste mit chronischen Nasennebenh\u00f6hlenproblemen, kognitiver Verwirrung oder stressbedingten Kopfschmerzen<br><b>Vamana (therapeutisches Erbrechen): <\/b>Sofern klinisch angezeigt, wird ein kontrolliertes Brechverfahren durchgef\u00fchrt, um den Magen und die oberen Atemwege von angesammeltem Kapha zu befreien \u2013 dies ist vorteilhaft f\u00fcr G\u00e4ste mit chronischen Schleimbeschwerden, Atemwegsproblemen oder \u00dcbergewicht, das auf ein Stoffwechselungleichgewicht zur\u00fcckzuf\u00fchren ist\n<\/div>\n<\/div><\/div><div class=\"bde-columns-11336-140 bde-columns\" data-entrance=\"slideUp\"><div class=\"bde-column-11336-252 bde-column\">\n  \n  \n\t\n\n\n\n<h6 class=\"bde-heading-11336-253 bde-heading\">\nPhase 3 \u2013 Regeneration: Wiederaufbau nach der Entgiftung\n<\/h6><div class=\"bde-text-11336-254 bde-text\">\nEine gr\u00fcndliche Entgiftung macht den K\u00f6rper aufnahmef\u00e4hig, schw\u00e4cht ihn aber vor\u00fcbergehend. Die Regenerationsphase sorgt daf\u00fcr, dass die positive Wirkung \u00fcber Ihren Aufenthalt hinaus anh\u00e4lt.<br><br><b>Rasayana-Therapie: <\/b>Wirksame ayurvedische Verj\u00fcngungsmittel \u2013 Chyawanprash, Ashwagandha Rasayana und individuell abgestimmte Kr\u00e4utertonika \u2013 zum Wiederaufbau von Ojas (Lebenskraft und Zellvitalit\u00e4t) nach der Entschlackung<br><b>Protokoll zur Darmregeneration: <\/b>Eine gezielte Ern\u00e4hrungstherapie mit Probiotika und Pr\u00e4biotika in Kombination mit Verdauungsenzymen zur Wiederherstellung der Darmflora nach einer gr\u00fcndlichen Darmreinigung<br><b>Neubewertung der funktionellen Medizin: <\/b>Blutwerte, Leberwerte und Entz\u00fcndungsmarker werden erneut untersucht, um eine messbare klinische Besserung nachzuweisen<br><b>Startseite \u2013 Protokollentwurf:<\/b> Vor Ihrer Abreise erhalten Sie einen detaillierten Nachbehandlungsplan \u2013 mit Kr\u00e4uterrezepturen, Ern\u00e4hrungsempfehlungen und Tipps zur Lebensweise, die darauf abzielen, Ihre Ergebnisse auch noch Monate nach Ihrer R\u00fcckkehr nach Europa aufrechtzuerhalten und zu vertiefen\n<\/div>\n<\/div><\/div><\/div>\n<\/section><section class=\"bde-section-11336-157 bde-section\">\n  \n  \n\t\n\n\n\n<div class=\"section-container\"><div class=\"bde-div-11336-158 bde-div\" data-entrance=\"slideUp\">\n  \n  \n\t\n\n\n\n<h2 class=\"bde-heading-11336-159 bde-heading\">\nF\u00fcr wen dieses Programm gedacht ist\n<\/h2><div class=\"bde-text-11336-160 bde-text\">\nDas \u201eTigris Valley Detox &amp; Cleanse\u201c-Programm richtet sich an G\u00e4ste aus Europa, auf die einer der folgenden Punkte zutrifft:\n<\/div>\n<\/div><div class=\"bde-columns-11336-161 bde-columns\"><div class=\"bde-column-11336-162 bde-column\" data-entrance=\"slideUp\">\n  \n  \n\t\n\n\n\n<div class=\"bde-div-11336-163 bde-div\">\n  \n  \n\t\n\n\n\n<h5 class=\"bde-heading-11336-164 bde-heading\">\n\u00dcberlastung in der Stadt:\n<\/h5><div class=\"bde-text-11336-165 bde-text\">\nDu lebst in einer Stadt und sp\u00fcrst die Belastung durch Umwelt- und Sinnesbelastungen \u2013 auf deiner Haut, in deiner Energie, bei deiner Verdauung und in deiner geistigen Klarheit<br>\n<\/div>\n<\/div><div class=\"bde-div-11336-166 bde-div\">\n  \n  \n\t\n\n\n\n<h5 class=\"bde-heading-11336-167 bde-heading\">\nBelastung durch Schwermetalle oder Chemikalien:\n<\/h5><div class=\"bde-text-11336-168 bde-text\">\nBerufliche Exposition (Zahnmedizin, Bauwesen, Kunst, verarbeitendes Gewerbe) oder l\u00e4ngerer Kontakt mit verunreinigtem Wasser oder Lebensmitteln<br>\n<\/div>\n<\/div><div class=\"bde-div-11336-226 bde-div\">\n  \n  \n\t\n\n\n\n<h5 class=\"bde-heading-11336-227 bde-heading\">\nHauterkrankungen:\n<\/h5><div class=\"bde-text-11336-228 bde-text\">\nEkzeme, Psoriasis, Akne oder unerkl\u00e4rliche Hautausschl\u00e4ge \u2013 Erkrankungen, die in der ayurvedischen Medizin durchweg auf eine Anh\u00e4ufung innerer Giftstoffe und eine \u00dcberlastung der Leber zur\u00fcckgef\u00fchrt werden<br>\n<\/div>\n<\/div><div class=\"bde-div-11336-229 bde-div\">\n  \n  \n\t\n\n\n\n<h5 class=\"bde-heading-11336-230 bde-heading\">\nDer Wunsch nach einem echten Neuanfang:\n<\/h5><div class=\"bde-text-11336-231 bde-text\">\nEs geht dir im Grunde genommen gut, aber du hast das Gef\u00fchl, dass sich die Belastungen der letzten Jahre auf deine Lebenskraft ausgewirkt haben \u2013 und du m\u00f6chtest sie wieder zur\u00fcckgewinnen, und zwar vollst\u00e4ndig, nicht nur schrittweise\n<\/div>\n<\/div>\n<\/div><div class=\"bde-column-11336-169 bde-column\" data-entrance=\"slideUp\">\n  \n  \n\t\n\n\n\n<div class=\"bde-div-11336-170 bde-div\">\n  \n  \n\t\n\n\n\n<h5 class=\"bde-heading-11336-171 bde-heading\">\nBelastung nach der Einnahme von Arzneimitteln:\n<\/h5><div class=\"bde-text-11336-172 bde-text\">\nLangfristige Einnahme von Antibiotika, hormonellen Verh\u00fctungsmitteln, Schmerzmitteln oder anderen Medikamenten, die die Darmflora und die Leberfunktion beeintr\u00e4chtigt haben<br>\n<\/div>\n<\/div><div class=\"bde-div-11336-173 bde-div\">\n  \n  \n\t\n\n\n\n<h5 class=\"bde-heading-11336-174 bde-heading\">\nChronische Verdauungsst\u00f6rungen:\n<\/h5><div class=\"bde-text-11336-175 bde-text\">\nReizdarmsyndrom, Bl\u00e4hungen, Verstopfung, Leaky-Gut-Syndrom, Nahrungsmittelunvertr\u00e4glichkeiten, die sich bisher jeder naturheilkundlichen oder ern\u00e4hrungsbezogenen Behandlung in Europa entzogen haben<br>\n<\/div>\n<\/div><div class=\"bde-div-11336-223 bde-div\">\n  \n  \n\t\n\n\n\n<h5 class=\"bde-heading-11336-224 bde-heading\">\nStoffwechseltr\u00e4gheit: \n<\/h5><div class=\"bde-text-11336-225 bde-text\">\nUnerkl\u00e4rliche Gewichtszunahme, eine M\u00fcdigkeit, die in keinem Verh\u00e4ltnis zum Lebensstil steht, sowie geistige Tr\u00e4gheit, die trotz ausreichendem Schlaf und guter Ern\u00e4hrung anh\u00e4lt<br>\n<\/div>\n<\/div>\n<\/div><\/div><\/div>\n<\/section><section class=\"bde-section-11336-261 bde-section\">\n  \n  \n\t\n\n\n\n<div class=\"section-container\"><div class=\"bde-div-11336-262 bde-div\">\n  \n  \n\t\n\n\n\n<h2 class=\"bde-heading-11336-263 bde-heading\" data-entrance=\"slideUp\">\nIhr Aufenthalt \u2013 Wie der Alltag w\u00e4hrend des Programms aussieht\n<\/h2><div class=\"bde-text-11336-303 bde-text\">\nEurop\u00e4ische G\u00e4ste sagen uns oft, dass die Umgebung schon die halbe Miete ist. Das Tigris Valley liegt in den bewaldeten H\u00fcgeln von Kerala \u2013 Berge, saubere Luft, Stille und eine Artenvielfalt, die der K\u00f6rper auf einer fast zellul\u00e4ren Ebene als einen Ort wahrnimmt, an dem man sich getrost fallen lassen kann.\n<\/div>\n<\/div><div class=\"bde-advancedslider-11336-264 bde-advancedslider\" data-entrance=\"slideUp\">\n<div class=\"breakdance-swiper-wrapper\" data-swiper-id=\"264\">\n  <div class=\"swiper\">\n    <div class=\"swiper-wrapper\">\n      <div class=\"bde-advancedslide-11336-265 bde-advancedslide swiper-slide\"><div class=\"advanced-slider__slide\">\n  <div class=\"bde-div-11336-266 bde-div\">\n  \n  \n\t\n\n\n\n<div id=\"icon_bx_btn\" class=\"bde-icon-box-11336-268 bde-icon-box\">\n\n    \n            <div class=\"ee-iconbox-icon breakdance-icon-atom\" >\n    \n                    <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 352 512\"><!-- Font Awesome Free 5.15.1 by @fontawesome - https:\/\/fontawesome.com License - https:\/\/fontawesome.com\/license\/free (Icons: CC BY 4.0, Fonts: SIL OFL 1.1, Code: MIT License) --><path d=\"M176 80c-52.94 0-96 43.06-96 96 0 8.84 7.16 16 16 16s16-7.16 16-16c0-35.3 28.72-64 64-64 8.84 0 16-7.16 16-16s-7.16-16-16-16zM96.06 459.17c0 3.15.93 6.22 2.68 8.84l24.51 36.84c2.97 4.46 7.97 7.14 13.32 7.14h78.85c5.36 0 10.36-2.68 13.32-7.14l24.51-36.84c1.74-2.62 2.67-5.7 2.68-8.84l.05-43.18H96.02l.04 43.18zM176 0C73.72 0 0 82.97 0 176c0 44.37 16.45 84.85 43.56 115.78 16.64 18.99 42.74 58.8 52.42 92.16v.06h48v-.12c-.01-4.77-.72-9.51-2.15-14.07-5.59-17.81-22.82-64.77-62.17-109.67-20.54-23.43-31.52-53.15-31.61-84.14-.2-73.64 59.67-128 127.95-128 70.58 0 128 57.42 128 128 0 30.97-11.24 60.85-31.65 84.14-39.11 44.61-56.42 91.47-62.1 109.46a47.507 47.507 0 0 0-2.22 14.3v.1h48v-.05c9.68-33.37 35.78-73.18 52.42-92.16C335.55 260.85 352 220.37 352 176 352 78.8 273.2 0 176 0z\"\/><\/svg>\n        \n        \n        \n            <\/div>\n    \n\n<div class=\"ee-iconbox-content\">\n      <h5 class=\"ee-iconbox-title bde-h3\" >Morgen<\/h5>\n        <div class=\"ee-iconbox-text\" >Sie wachen ohne Wecker auf. Ein warmes Kr\u00e4uter-Kashayam \u2013 Ihr ganz pers\u00f6nlicher Morgentee \u2013 wird Ihnen auf Ihr Zimmer gebracht. Auf das Sonnenaufgang-Yoga auf der Au\u00dfenplattform unter Anleitung eines zertifizierten therapeutischen Lehrers folgt ein Gespr\u00e4ch mit dem Arzt, bei dem die Reaktion auf die Behandlung des Vortags besprochen und gegebenenfalls Anpassungen vorgenommen werden.<\/div>\n    <\/div>\n\n<\/div>\n<\/div>\n<\/div><\/div><div class=\"bde-advancedslide-11336-269 bde-advancedslide swiper-slide\"><div class=\"advanced-slider__slide\">\n  <div class=\"bde-div-11336-270 bde-div\">\n  \n  \n\t\n\n\n\n<div class=\"bde-icon-box-11336-272 bde-icon-box\">\n\n    \n            <div class=\"ee-iconbox-icon breakdance-icon-atom\" >\n    \n                    <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 352 512\"><!-- Font Awesome Free 5.15.1 by @fontawesome - https:\/\/fontawesome.com License - https:\/\/fontawesome.com\/license\/free (Icons: CC BY 4.0, Fonts: SIL OFL 1.1, Code: MIT License) --><path d=\"M176 80c-52.94 0-96 43.06-96 96 0 8.84 7.16 16 16 16s16-7.16 16-16c0-35.3 28.72-64 64-64 8.84 0 16-7.16 16-16s-7.16-16-16-16zM96.06 459.17c0 3.15.93 6.22 2.68 8.84l24.51 36.84c2.97 4.46 7.97 7.14 13.32 7.14h78.85c5.36 0 10.36-2.68 13.32-7.14l24.51-36.84c1.74-2.62 2.67-5.7 2.68-8.84l.05-43.18H96.02l.04 43.18zM176 0C73.72 0 0 82.97 0 176c0 44.37 16.45 84.85 43.56 115.78 16.64 18.99 42.74 58.8 52.42 92.16v.06h48v-.12c-.01-4.77-.72-9.51-2.15-14.07-5.59-17.81-22.82-64.77-62.17-109.67-20.54-23.43-31.52-53.15-31.61-84.14-.2-73.64 59.67-128 127.95-128 70.58 0 128 57.42 128 128 0 30.97-11.24 60.85-31.65 84.14-39.11 44.61-56.42 91.47-62.1 109.46a47.507 47.507 0 0 0-2.22 14.3v.1h48v-.05c9.68-33.37 35.78-73.18 52.42-92.16C335.55 260.85 352 220.37 352 176 352 78.8 273.2 0 176 0z\"\/><\/svg>\n        \n        \n        \n            <\/div>\n    \n\n<div class=\"ee-iconbox-content\">\n      <h5 class=\"ee-iconbox-title bde-h3\" >Mittags:<\/h5>\n        <div class=\"ee-iconbox-text\" >Ihre Behandlungssitzungen \u2013 in der Regel 2 bis 4 Stunden individuelle Therapien \u2013 werden nach den nat\u00fcrlichen Energierhythmen des K\u00f6rpers geplant und niemals \u00fcberst\u00fcrzt durchgef\u00fchrt. Abhyanga vor Swedana. Nasya vor der Ruhephase. Jede Abfolge ist auf eine bestimmte klinische Wirkung ausgerichtet.<\/div>\n    <\/div>\n\n<\/div>\n<\/div>\n<\/div><\/div><div class=\"bde-advancedslide-11336-273 bde-advancedslide swiper-slide\"><div class=\"advanced-slider__slide\">\n  <div class=\"bde-div-11336-274 bde-div\">\n  \n  \n\t\n\n\n\n<div class=\"bde-icon-box-11336-276 bde-icon-box\">\n\n    \n            <div class=\"ee-iconbox-icon breakdance-icon-atom\" >\n    \n                    <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 352 512\"><!-- Font Awesome Free 5.15.1 by @fontawesome - https:\/\/fontawesome.com License - https:\/\/fontawesome.com\/license\/free (Icons: CC BY 4.0, Fonts: SIL OFL 1.1, Code: MIT License) --><path d=\"M176 80c-52.94 0-96 43.06-96 96 0 8.84 7.16 16 16 16s16-7.16 16-16c0-35.3 28.72-64 64-64 8.84 0 16-7.16 16-16s-7.16-16-16-16zM96.06 459.17c0 3.15.93 6.22 2.68 8.84l24.51 36.84c2.97 4.46 7.97 7.14 13.32 7.14h78.85c5.36 0 10.36-2.68 13.32-7.14l24.51-36.84c1.74-2.62 2.67-5.7 2.68-8.84l.05-43.18H96.02l.04 43.18zM176 0C73.72 0 0 82.97 0 176c0 44.37 16.45 84.85 43.56 115.78 16.64 18.99 42.74 58.8 52.42 92.16v.06h48v-.12c-.01-4.77-.72-9.51-2.15-14.07-5.59-17.81-22.82-64.77-62.17-109.67-20.54-23.43-31.52-53.15-31.61-84.14-.2-73.64 59.67-128 127.95-128 70.58 0 128 57.42 128 128 0 30.97-11.24 60.85-31.65 84.14-39.11 44.61-56.42 91.47-62.1 109.46a47.507 47.507 0 0 0-2.22 14.3v.1h48v-.05c9.68-33.37 35.78-73.18 52.42-92.16C335.55 260.85 352 220.37 352 176 352 78.8 273.2 0 176 0z\"\/><\/svg>\n        \n        \n        \n            <\/div>\n    \n\n<div class=\"ee-iconbox-content\">\n      <h5 class=\"ee-iconbox-title bde-h3\" >Nachmittag:<\/h5>\n        <div class=\"ee-iconbox-text\" >Freizeit. Hier gibt es keinen vollgepackten Zeitplan. Der Wald geh\u00f6rt ganz Ihnen \u2013 Wanderwege, der nat\u00fcrliche Wasserlauf, ruhige Sitzecken. Viele G\u00e4ste berichten, dass allein der Aufenthalt in dieser Umgebung, ohne Zeitplan und ohne Ablenkung, eine innere Ruhe bewirkt, die sie seit Jahren nicht mehr erlebt haben.<\/div>\n    <\/div>\n\n<\/div>\n<\/div>\n<\/div><\/div><div class=\"bde-advancedslide-11336-277 bde-advancedslide swiper-slide\"><div class=\"advanced-slider__slide\">\n  <div class=\"bde-div-11336-278 bde-div\">\n  \n  \n\t\n\n\n\n<div class=\"bde-icon-box-11336-280 bde-icon-box\">\n\n    \n            <div class=\"ee-iconbox-icon breakdance-icon-atom\" >\n    \n                    <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 352 512\"><!-- Font Awesome Free 5.15.1 by @fontawesome - https:\/\/fontawesome.com License - https:\/\/fontawesome.com\/license\/free (Icons: CC BY 4.0, Fonts: SIL OFL 1.1, Code: MIT License) --><path d=\"M176 80c-52.94 0-96 43.06-96 96 0 8.84 7.16 16 16 16s16-7.16 16-16c0-35.3 28.72-64 64-64 8.84 0 16-7.16 16-16s-7.16-16-16-16zM96.06 459.17c0 3.15.93 6.22 2.68 8.84l24.51 36.84c2.97 4.46 7.97 7.14 13.32 7.14h78.85c5.36 0 10.36-2.68 13.32-7.14l24.51-36.84c1.74-2.62 2.67-5.7 2.68-8.84l.05-43.18H96.02l.04 43.18zM176 0C73.72 0 0 82.97 0 176c0 44.37 16.45 84.85 43.56 115.78 16.64 18.99 42.74 58.8 52.42 92.16v.06h48v-.12c-.01-4.77-.72-9.51-2.15-14.07-5.59-17.81-22.82-64.77-62.17-109.67-20.54-23.43-31.52-53.15-31.61-84.14-.2-73.64 59.67-128 127.95-128 70.58 0 128 57.42 128 128 0 30.97-11.24 60.85-31.65 84.14-39.11 44.61-56.42 91.47-62.1 109.46a47.507 47.507 0 0 0-2.22 14.3v.1h48v-.05c9.68-33.37 35.78-73.18 52.42-92.16C335.55 260.85 352 220.37 352 176 352 78.8 273.2 0 176 0z\"\/><\/svg>\n        \n        \n        \n            <\/div>\n    \n\n<div class=\"ee-iconbox-content\">\n      <h5 class=\"ee-iconbox-title bde-h3\" >Abend: <\/h5>\n        <div class=\"ee-iconbox-text\" >Eine leichte, wohltuende Mahlzeit, zubereitet von unserer Ayurveda-Ern\u00e4hrungsberaterin. Gruppenmeditation. Ein Schlaf, den die meisten G\u00e4ste am Ende der ersten Woche als den tiefsten und erholsamsten bezeichnen, den sie seit Jahren erlebt haben.<\/div>\n    <\/div>\n\n<\/div>\n<\/div>\n<\/div><\/div>\n    <\/div>\n  <\/div>\n\n              <div class=\"swiper-button-prev\">\n            <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 320 512\"><!--! Font Awesome Free 6.5.1 by @fontawesome - https:\/\/fontawesome.com License - https:\/\/fontawesome.com\/license\/free (Icons: CC BY 4.0, Fonts: SIL OFL 1.1, Code: MIT License) Copyright 2023 Fonticons, Inc. --><path d=\"M41.4 233.4c-12.5 12.5-12.5 32.8 0 45.3l160 160c12.5 12.5 32.8 12.5 45.3 0s12.5-32.8 0-45.3L109.3 256 246.6 118.6c12.5-12.5 12.5-32.8 0-45.3s-32.8-12.5-45.3 0l-160 160z\"\/><\/svg>\n        <\/div>\n        <div class=\"swiper-button-next\">\n            <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 320 512\"><!--! Font Awesome Free 6.5.1 by @fontawesome - https:\/\/fontawesome.com License - https:\/\/fontawesome.com\/license\/free (Icons: CC BY 4.0, Fonts: SIL OFL 1.1, Code: MIT License) Copyright 2023 Fonticons, Inc. --><path d=\"M278.6 233.4c12.5 12.5 12.5 32.8 0 45.3l-160 160c-12.5 12.5-32.8 12.5-45.3 0s-12.5-32.8 0-45.3L210.7 256 73.4 118.6c-12.5-12.5-12.5-32.8 0-45.3s32.8-12.5 45.3 0l160 160z\"\/><\/svg>\n        <\/div>\n    \n    \n<\/div>\n\n<\/div><div class=\"bde-div-11336-301 bde-div\" data-entrance=\"slideUp\">\n  \n  \n\t\n\n\n\n<div class=\"bde-button-11336-302 bde-button\">\n        \n    \n    \n    \n    \n            \n                    \n            \n            \n\n    \n    \n    \n    \n    \n    <a class=\"breakdance-link button-atom button-atom--primary bde-button__button\" href=\"\/de\/ayush\/\" target=\"_self\" data-type=\"url\"  >\n\n    \n        <span class=\"button-atom__text\">Erkunden Sie <\/span>\n\n        \n        \n                <\/a>\n\n    \n\n\n<\/div>\n<\/div><\/div>\n<\/section><section class=\"bde-section-11336-191 bde-section\">\n  \n  \n\t\n\n\n\n<div class=\"section-container\"><div class=\"bde-div-11336-195 bde-div\" data-entrance=\"slideUp\">\n  \n  \n\t\n\n\n\n<h3 class=\"bde-heading-11336-198 bde-heading\">\nPraktischer Leitfaden f\u00fcr Reisende aus Europa \u2013 Reisen, Visa und Anreise\n<\/h3><div class=\"bde-text-11336-199 bde-text\">\nEine Reise von Europa nach Kerala zur medizinischen Behandlung ist einfacher, als viele G\u00e4ste zun\u00e4chst annehmen. Hier finden Sie alles, was Sie wissen m\u00fcssen:\n<\/div><div class=\"bde-columns-11336-196 bde-columns\"><div class=\"bde-column-11336-200 bde-column\">\n  \n  \n\t\n\n\n\n<div class=\"bde-grid-11336-201 bde-grid\">\n  \n  \n\t\n\n\n\n<div class=\"bde-div-11336-202 bde-div\">\n  \n  \n\t\n\n\n\n<div class=\"bde-image-11336-203 bde-image\">\n<figure class=\"breakdance-image breakdance-image--592\">\n\t<div class=\"breakdance-image-container\">\n\t\t<div class=\"breakdance-image-clip\"><img loading=\"lazy\" decoding=\"async\" class=\"breakdance-image-object\" src=\"https:\/\/tigrisvalley.com\/wp-content\/uploads\/2025\/06\/7.png\" width=\"58\" height=\"58\" sizes=\"auto, (max-width: 58px) 100vw, 58px\"><\/div>\n\t<\/div><\/figure>\n\n<\/div><h6 class=\"bde-heading-11336-204 bde-heading\">\nN\u00e4chstgelegene Flugh\u00e4fen:\n<\/h6><div class=\"bde-text-11336-205 bde-text\">\nInternationaler Flughafen Calicut (CCJ), 2 Stunden vom Tigris-Tal entfernt \u2013 Direktverbindungen von mehreren europ\u00e4ischen Drehkreuzen \u00fcber Fluggesellschaften aus der Golfregion; Internationaler Flughafen Kochi (COK), 4 Stunden entfernt\n<\/div>\n<\/div><div class=\"bde-div-11336-206 bde-div\">\n  \n  \n\t\n\n\n\n<div class=\"bde-image-11336-207 bde-image\">\n<figure class=\"breakdance-image breakdance-image--908\">\n\t<div class=\"breakdance-image-container\">\n\t\t<div class=\"breakdance-image-clip\"><img loading=\"lazy\" decoding=\"async\" class=\"breakdance-image-object\" src=\"https:\/\/tigrisvalley.com\/wp-content\/uploads\/2025\/06\/communication_18665096-1.png\" width=\"58\" height=\"58\" sizes=\"auto, (max-width: 58px) 100vw, 58px\"><\/div>\n\t<\/div><\/figure>\n\n<\/div><h6 class=\"bde-heading-11336-208 bde-heading\">\nFlugverbindungen aus Europa:\n<\/h6><div class=\"bde-text-11336-209 bde-text\">\nDirektverbindungen \u00fcber Dubai (Emirates), Doha (Qatar Airways), Abu Dhabi (Etihad) und Istanbul (Turkish Airlines) von gro\u00dfen europ\u00e4ischen St\u00e4dten wie London, Frankfurt, Amsterdam, Paris, Mailand, Madrid, Z\u00fcrich und Wien<br>\n<\/div>\n<\/div><div class=\"bde-div-11336-210 bde-div\">\n  \n  \n\t\n\n\n\n<div class=\"bde-image-11336-211 bde-image\">\n<figure class=\"breakdance-image breakdance-image--594\">\n\t<div class=\"breakdance-image-container\">\n\t\t<div class=\"breakdance-image-clip\"><img loading=\"lazy\" decoding=\"async\" class=\"breakdance-image-object\" src=\"https:\/\/tigrisvalley.com\/wp-content\/uploads\/2025\/06\/9.png\" width=\"58\" height=\"58\" sizes=\"auto, (max-width: 58px) 100vw, 58px\"><\/div>\n\t<\/div><\/figure>\n\n<\/div><h6 class=\"bde-heading-11336-212 bde-heading\">\nFlugdauer: \n<\/h6><div class=\"bde-text-11336-213 bde-text\">\nEtwa 9 bis 11 Stunden von Westeuropa nach Calicut oder Kochi, in der Regel mit einem kurzen Umsteigen<br>\n<\/div>\n<\/div><div class=\"bde-div-11336-214 bde-div\">\n  \n  \n\t\n\n\n\n<div class=\"bde-image-11336-215 bde-image\">\n<figure class=\"breakdance-image breakdance-image--632\">\n\t<div class=\"breakdance-image-container\">\n\t\t<div class=\"breakdance-image-clip\"><img loading=\"lazy\" decoding=\"async\" class=\"breakdance-image-object\" src=\"https:\/\/tigrisvalley.com\/wp-content\/uploads\/2025\/06\/3-2.png\" width=\"58\" height=\"58\" sizes=\"auto, (max-width: 58px) 100vw, 58px\"><\/div>\n\t<\/div><\/figure>\n\n<\/div><h6 class=\"bde-heading-11336-216 bde-heading\">\nW\u00e4hrung:\n<\/h6><div class=\"bde-text-11336-217 bde-text\">\nIndische Rupie (INR). Internationale Kredit- und Debitkarten werden akzeptiert; f\u00fcr die Anzahlung auf das Programm sind Bank\u00fcberweisungen m\u00f6glich\n<\/div>\n<\/div><div class=\"bde-div-11336-219 bde-div\">\n  \n  \n\t\n\n\n\n<div class=\"bde-image-11336-220 bde-image\">\n<figure class=\"breakdance-image breakdance-image--1214\">\n\t<div class=\"breakdance-image-container\">\n\t\t<div class=\"breakdance-image-clip\"><img loading=\"lazy\" decoding=\"async\" class=\"breakdance-image-object\" src=\"https:\/\/tigrisvalley.com\/wp-content\/uploads\/2025\/06\/Dinner.png\" width=\"40\" height=\"40\" sizes=\"auto, (max-width: 40px) 100vw, 40px\"><\/div>\n\t<\/div><\/figure>\n\n<\/div><h6 class=\"bde-heading-11336-221 bde-heading\">\nFlughafen-Transfer: \n<\/h6><div class=\"bde-text-11336-222 bde-text\">\nWir organisieren die Abholung direkt vom Flughafen und den Transfer ins Tigris-Tal \u2013 so m\u00fcssen Sie sich nach einem langen Flug nicht auf unbekannten Stra\u00dfen zurechtfinden\n<\/div>\n<\/div><div class=\"bde-div-11336-304 bde-div\">\n  \n  \n\t\n\n\n\n<div class=\"bde-image-11336-305 bde-image\">\n<figure class=\"breakdance-image breakdance-image--1214\">\n\t<div class=\"breakdance-image-container\">\n\t\t<div class=\"breakdance-image-clip\"><img loading=\"lazy\" decoding=\"async\" class=\"breakdance-image-object\" src=\"https:\/\/tigrisvalley.com\/wp-content\/uploads\/2025\/06\/Dinner.png\" width=\"40\" height=\"40\" sizes=\"auto, (max-width: 40px) 100vw, 40px\"><\/div>\n\t<\/div><\/figure>\n\n<\/div><h6 class=\"bde-heading-11336-306 bde-heading\">\nZeitzone: \n<\/h6><div class=\"bde-text-11336-307 bde-text\">\nIn Kerala gilt die indische Standardzeit (IST, UTC+5:30) \u2013 3,5 bis 4,5 Stunden vor der mitteleurop\u00e4ischen Zeit. Die meisten europ\u00e4ischen G\u00e4ste gew\u00f6hnen sich innerhalb von zwei Tagen daran, unterst\u00fctzt durch unsere Ma\u00dfnahmen zur F\u00f6rderung des Tagesrhythmus\n<\/div>\n<\/div><div class=\"bde-div-11336-312 bde-div\">\n  \n  \n\t\n\n\n\n<div class=\"bde-image-11336-313 bde-image\">\n<figure class=\"breakdance-image breakdance-image--1214\">\n\t<div class=\"breakdance-image-container\">\n\t\t<div class=\"breakdance-image-clip\"><img loading=\"lazy\" decoding=\"async\" class=\"breakdance-image-object\" src=\"https:\/\/tigrisvalley.com\/wp-content\/uploads\/2025\/06\/Dinner.png\" width=\"40\" height=\"40\" sizes=\"auto, (max-width: 40px) 100vw, 40px\"><\/div>\n\t<\/div><\/figure>\n\n<\/div><h6 class=\"bde-heading-11336-314 bde-heading\">\nStudienkosten im Vergleich zu europ\u00e4ischen \u00c4quivalenten: \n<\/h6><div class=\"bde-text-11336-315 bde-text\">\nEine medizinisch betreute Panchakarma-Entgiftungskur im Tigris Valley \u2013 inklusive Unterkunft, aller Mahlzeiten, unbegrenzter \u00e4rztlicher Beratung und t\u00e4glicher Behandlungen \u2013 kostet nur einen Bruchteil dessen, was vergleichbare Programme in europ\u00e4ischen Ayurveda- oder Naturheilzentren (Schweiz, \u00d6sterreich, Deutschland oder Spanien) kosten, selbst wenn man die internationalen Fl\u00fcge mit einrechnet\n<\/div>\n<\/div><div class=\"bde-div-11336-308 bde-div\">\n  \n  \n\t\n\n\n\n<div class=\"bde-image-11336-309 bde-image\">\n<figure class=\"breakdance-image breakdance-image--1214\">\n\t<div class=\"breakdance-image-container\">\n\t\t<div class=\"breakdance-image-clip\"><img loading=\"lazy\" decoding=\"async\" class=\"breakdance-image-object\" src=\"https:\/\/tigrisvalley.com\/wp-content\/uploads\/2025\/06\/Dinner.png\" width=\"40\" height=\"40\" sizes=\"auto, (max-width: 40px) 100vw, 40px\"><\/div>\n\t<\/div><\/figure>\n\n<\/div><h6 class=\"bde-heading-11336-310 bde-heading\">\nIndisches E-Visum (E-Touristen- oder E-Medizinvisum): \n<\/h6><div class=\"bde-text-11336-311 bde-text\">\nStaatsangeh\u00f6rige der meisten europ\u00e4ischen L\u00e4nder k\u00f6nnen ihren Antrag online unter indianvisaonline.gov.in stellen \u2013 die Bearbeitung erfolgt in der Regel innerhalb von 48 bis 72 Stunden. Auf Wunsch stellt unser Team f\u00fcr internationale Patienten alle f\u00fcr die Beantragung eines medizinischen Visums erforderlichen Behandlungsunterlagen zur Verf\u00fcgung.<br>\n<\/div>\n<\/div>\n<\/div>\n<\/div><\/div>\n<\/div><\/div>\n<\/section><section class=\"bde-section-11336-238 bde-section\">\n  \n  \n\t\n\n\n\n<div class=\"section-container\"><div class=\"bde-fancy-testimonial-11336-239 bde-fancy-testimonial\">\n<div class='bde-fancy-testimonial_image'>\n  <img loading=\"lazy\" decoding=\"async\" class=\"breakdance-image-object\" src=\"https:\/\/tigrisvalley.com\/wp-content\/uploads\/2025\/06\/Group.png\" width=\"993\" height=\"589\" srcset=\"https:\/\/tigrisvalley.com\/wp-content\/uploads\/2025\/06\/Group.png 993w, https:\/\/tigrisvalley.com\/wp-content\/uploads\/2025\/06\/Group-300x178.png 300w, https:\/\/tigrisvalley.com\/wp-content\/uploads\/2025\/06\/Group-768x456.png 768w\" sizes=\"auto, (max-width: 993px) 100vw, 993px\">\n<\/div>\n<div class='bde-fancy-testimonial_content'>\n    <div class='bde-fancy-testimonial_title' >\n    Was europ\u00e4ische G\u00e4ste \u00fcber ihre Erfahrungen sagen\n  <\/div>\n  \n  <div class='bde-fancy-testimonial_text'>\n        <div class=\"bde-fancy-testimonial_quote\" aria-hidden=\"true\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"icon-quotes-left\" viewbox=\"0 0 32 32\">\r\n<path d=\"M7.031 14c3.866 0 7 3.134 7 7s-3.134 7-7 7-7-3.134-7-7l-0.031-1c0-7.732 6.268-14 14-14v4c-2.671 0-5.182 1.040-7.071 2.929-0.364 0.364-0.695 0.751-0.995 1.157 0.357-0.056 0.724-0.086 1.097-0.086zM25.031 14c3.866 0 7 3.134 7 7s-3.134 7-7 7-7-3.134-7-7l-0.031-1c0-7.732 6.268-14 14-14v4c-2.671 0-5.182 1.040-7.071 2.929-0.364 0.364-0.695 0.751-0.995 1.157 0.358-0.056 0.724-0.086 1.097-0.086z\"\/>\r\n<\/svg><\/div>\n    <div class=\"bde-fancy-testimonial_quote\" aria-hidden=\"true\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"icon-quotes-left\" viewbox=\"0 0 32 32\">\r\n<path d=\"M7.031 14c3.866 0 7 3.134 7 7s-3.134 7-7 7-7-3.134-7-7l-0.031-1c0-7.732 6.268-14 14-14v4c-2.671 0-5.182 1.040-7.071 2.929-0.364 0.364-0.695 0.751-0.995 1.157 0.357-0.056 0.724-0.086 1.097-0.086zM25.031 14c3.866 0 7 3.134 7 7s-3.134 7-7 7-7-3.134-7-7l-0.031-1c0-7.732 6.268-14 14-14v4c-2.671 0-5.182 1.040-7.071 2.929-0.364 0.364-0.695 0.751-0.995 1.157 0.358-0.056 0.724-0.086 1.097-0.086z\"\/>\r\n<\/svg><\/div>\n        <p  class='bde-fancy-testimonial_text_text'>\"Ich kam aus Berlin mit zw\u00f6lf Jahren angesammeltem Stress im Gep\u00e4ck \u2013 schlechte Verdauung, st\u00e4ndige Hautausschl\u00e4ge, M\u00fcdigkeit, die sich durch keinen noch so langen Schlaf beheben lie\u00df. Mein deutscher Heilpraktiker hatte alles versucht. Tigris Valley schaffte in drei Wochen, was drei Jahre Behandlung in Europa nicht geschafft hatten. Das Panchakarma war au\u00dfergew\u00f6hnlich \u2013 ich sah, wie sich meine Haut innerhalb weniger Tage kl\u00e4rte. Ich reiste mit einem Gef\u00fchl der Leichtigkeit, Reinheit und Klarheit ab, wie ich es seit \u00fcber einem Jahrzehnt nicht mehr erlebt hatte. Das medizinische Team hier k\u00fcmmert sich aufrichtig um einen, auf eine Weise, die ich nicht erwartet hatte.\"<br>\u2014 Miriam S., Berlin | 21-Tage-Entgiftungs- und Reinigungsprogramm (Panchakarma)<br><br><br>\"Ich kam aus Amsterdam, nachdem ich ein Jahrzehnt lang unter Reizdarmsyndrom, Nahrungsmittelunvertr\u00e4glichkeiten und einem Darm gelitten hatte, der einfach nie richtig funktionierte, obwohl ich alle in Europa verf\u00fcgbaren Behandlungsmethoden ausprobiert hatte. Das Team im Tigris Valley f\u00fchrte Untersuchungen durch, die kein Arzt in den Niederlanden jemals vorgeschlagen hatte, identifizierte die Ursache innerhalb von zwei Tagen und stellte darauf aufbauend ein Panchakarma-Programm zusammen. Am zehnten Tag hatte sich meine Verdauung bereits ver\u00e4ndert. Am Ende der drei Wochen war sie wie verwandelt. Ich kann diesen Ort jedem Europ\u00e4er, der sich von der Schulmedizin im Stich gelassen f\u00fchlt, nur w\u00e4rmstens empfehlen.\"<br>\u2014 Lars B., Amsterdam | 21-Tage-Programm zur Darmreinigung und Wiederherstellung der Verdauungsfunktion<\/p>\n  <\/div>\n              <div class='bde-fancy-testimonial_rate' role=\"img\" aria-label=\"5 von 5 Sternen\">\n                          <svg aria-hidden=\"true\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 576 512\"><path d=\"M259.3 17.8L194 150.2 47.9 171.5c-26.2 3.8-36.7 36.1-17.7 54.6l105.7 103-25 145.5c-4.5 26.3 23.2 46 46.4 33.7L288 439.6l130.7 68.7c23.2 12.2 50.9-7.4 46.4-33.7l-25-145.5 105.7-103c19-18.5 8.5-50.8-17.7-54.6L382 150.2 316.7 17.8c-11.7-23.6-45.6-23.9-57.4 0z\"\/><\/svg>\n\n                                  <svg aria-hidden=\"true\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 576 512\"><path d=\"M259.3 17.8L194 150.2 47.9 171.5c-26.2 3.8-36.7 36.1-17.7 54.6l105.7 103-25 145.5c-4.5 26.3 23.2 46 46.4 33.7L288 439.6l130.7 68.7c23.2 12.2 50.9-7.4 46.4-33.7l-25-145.5 105.7-103c19-18.5 8.5-50.8-17.7-54.6L382 150.2 316.7 17.8c-11.7-23.6-45.6-23.9-57.4 0z\"\/><\/svg>\n\n                                  <svg aria-hidden=\"true\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 576 512\"><path d=\"M259.3 17.8L194 150.2 47.9 171.5c-26.2 3.8-36.7 36.1-17.7 54.6l105.7 103-25 145.5c-4.5 26.3 23.2 46 46.4 33.7L288 439.6l130.7 68.7c23.2 12.2 50.9-7.4 46.4-33.7l-25-145.5 105.7-103c19-18.5 8.5-50.8-17.7-54.6L382 150.2 316.7 17.8c-11.7-23.6-45.6-23.9-57.4 0z\"\/><\/svg>\n\n                                  <svg aria-hidden=\"true\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 576 512\"><path d=\"M259.3 17.8L194 150.2 47.9 171.5c-26.2 3.8-36.7 36.1-17.7 54.6l105.7 103-25 145.5c-4.5 26.3 23.2 46 46.4 33.7L288 439.6l130.7 68.7c23.2 12.2 50.9-7.4 46.4-33.7l-25-145.5 105.7-103c19-18.5 8.5-50.8-17.7-54.6L382 150.2 316.7 17.8c-11.7-23.6-45.6-23.9-57.4 0z\"\/><\/svg>\n\n                                  <svg aria-hidden=\"true\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 576 512\"><path d=\"M259.3 17.8L194 150.2 47.9 171.5c-26.2 3.8-36.7 36.1-17.7 54.6l105.7 103-25 145.5c-4.5 26.3 23.2 46 46.4 33.7L288 439.6l130.7 68.7c23.2 12.2 50.9-7.4 46.4-33.7l-25-145.5 105.7-103c19-18.5 8.5-50.8-17.7-54.6L382 150.2 316.7 17.8c-11.7-23.6-45.6-23.9-57.4 0z\"\/><\/svg>\n\n                  <\/div>\n        <\/div>\n\n<\/div><\/div>\n<\/section><section class=\"bde-section-11336-240 bde-section\">\n  \n  \n\t\n\n\n\n<div class=\"section-container\"><h3 class=\"bde-heading-11336-242 bde-heading\">\nIhre Fragen, beantwortet\n<\/h3><div class=\"bde-frequently-asked-questions-11336-241 bde-frequently-asked-questions\">\n      <div class=\"bde-faq__item\">\n      <h3 class=\"bde-faq__title-tag\">\n       <button id=\"bde-faq-241-button-1\" aria-expanded=\"false\" aria-controls=\"bde-faq-241-1\" class=\"bde-faq__question js-faq-item\">\n          <span class=\"bde-faq__title\"> Ist Panchakarma sicher, und welche Nebenwirkungen gibt es?<br><\/span>\n                           <div aria-hidden=\"true\" class=\"bde-faq__icon bde-faq__icon--inactive\">\n                                <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 32 32\">\r\n<path d=\"M31 12h-11v-11c0-0.552-0.448-1-1-1h-6c-0.552 0-1 0.448-1 1v11h-11c-0.552 0-1 0.448-1 1v6c0 0.552 0.448 1 1 1h11v11c0 0.552 0.448 1 1 1h6c0.552 0 1-0.448 1-1v-11h11c0.552 0 1-0.448 1-1v-6c0-0.552-0.448-1-1-1z\"\/>\r\n<\/svg>\n                            <\/div>\n         \t  <div aria-hidden=\"true\" class=\"bde-faq__icon bde-faq__icon--active\">\n                                <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 448 512\"><!-- Font Awesome Free 5.15.1 by @fontawesome - https:\/\/fontawesome.com License - https:\/\/fontawesome.com\/license\/free (Icons: CC BY 4.0, Fonts: SIL OFL 1.1, Code: MIT License) --><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"\/><\/svg>\n                            <\/div>\n                  <\/button>\n      <\/h3>\n      <div role=\"region\" aria-labelledby=\"bde-faq-241-button-1\" id=\"bde-faq-241-1\" class=\"bde-faq__answer\">\n        <div class=\"bde-faq__answer-content\">\n            <div class=\"breakdance-rich-text-styles\"><p>Wenn die Behandlung von ausgebildeten Ayurveda-\u00c4rzten nach einer ordnungsgem\u00e4\u00dfen diagnostischen Untersuchung und Vorbereitungsphase durchgef\u00fchrt wird \u2013 so wie es bei Tigris Valley der Fall ist \u2013 <em>Panchakarma<\/em> ist ein klinisch sicheres und gut vertr\u00e4gliches Verfahren. Bei einigen G\u00e4sten kommt es in der fr\u00fchen Reinigungsphase zu einer kurzen Phase der M\u00fcdigkeit oder zu erh\u00f6hter emotionaler Empfindlichkeit, die unsere \u00c4rzte genau beobachten und als Zeichen einer wirksamen Entgiftung betrachten. Wir f\u00fchren Panchakarma nur nach gr\u00fcndlicher Vorbereitung und unter st\u00e4ndiger \u00e4rztlicher Aufsicht durch.<\/p><\/div>\n\n                    <\/div>\n      <\/div>\n    <\/div>\n      <div class=\"bde-faq__item\">\n      <h3 class=\"bde-faq__title-tag\">\n       <button id=\"bde-faq-241-button-2\" aria-expanded=\"false\" aria-controls=\"bde-faq-241-2\" class=\"bde-faq__question js-faq-item\">\n          <span class=\"bde-faq__title\">Wie lange sollte ich bleiben, damit der Entgiftungsaufenthalt wirklich Wirkung zeigt?<\/span>\n                           <div aria-hidden=\"true\" class=\"bde-faq__icon bde-faq__icon--inactive\">\n                                <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 32 32\">\r\n<path d=\"M31 12h-11v-11c0-0.552-0.448-1-1-1h-6c-0.552 0-1 0.448-1 1v11h-11c-0.552 0-1 0.448-1 1v6c0 0.552 0.448 1 1 1h11v11c0 0.552 0.448 1 1 1h6c0.552 0 1-0.448 1-1v-11h11c0.552 0 1-0.448 1-1v-6c0-0.552-0.448-1-1-1z\"\/>\r\n<\/svg>\n                            <\/div>\n         \t  <div aria-hidden=\"true\" class=\"bde-faq__icon bde-faq__icon--active\">\n                                <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 448 512\"><!-- Font Awesome Free 5.15.1 by @fontawesome - https:\/\/fontawesome.com License - https:\/\/fontawesome.com\/license\/free (Icons: CC BY 4.0, Fonts: SIL OFL 1.1, Code: MIT License) --><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"\/><\/svg>\n                            <\/div>\n                  <\/button>\n      <\/h3>\n      <div role=\"region\" aria-labelledby=\"bde-faq-241-button-2\" id=\"bde-faq-241-2\" class=\"bde-faq__answer\">\n        <div class=\"bde-faq__answer-content\">\n            <div class=\"breakdance-rich-text-styles\"><p>Die empfohlene Mindestdauer des Programms betr\u00e4gt <strong>14 Tage<\/strong>. So bleibt gen\u00fcgend Zeit f\u00fcr alle drei Phasen \u2013 Vorbereitung, Entschlackung und Regeneration. F\u00fcr G\u00e4ste mit einer erheblichen toxischen Belastung, chronischen Verdauungsst\u00f6rungen, Hautproblemen oder Stoffwechselst\u00f6rungen, <strong>21 Tage<\/strong> f\u00fchrt zu wesentlich umfassenderen und l\u00e4nger anhaltenden Ergebnissen. Unsere Fach\u00e4rzte beraten Sie im Rahmen Ihrer kostenlosen Beratung vor der Anreise hinsichtlich der geeigneten Behandlungsdauer.<\/p><\/div>\n\n                    <\/div>\n      <\/div>\n    <\/div>\n      <div class=\"bde-faq__item\">\n      <h3 class=\"bde-faq__title-tag\">\n       <button id=\"bde-faq-241-button-3\" aria-expanded=\"false\" aria-controls=\"bde-faq-241-3\" class=\"bde-faq__question js-faq-item\">\n          <span class=\"bde-faq__title\">Muss ich mich w\u00e4hrend des Programms streng an eine Di\u00e4t halten?<\/span>\n                           <div aria-hidden=\"true\" class=\"bde-faq__icon bde-faq__icon--inactive\">\n                                <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 32 32\">\r\n<path d=\"M31 12h-11v-11c0-0.552-0.448-1-1-1h-6c-0.552 0-1 0.448-1 1v11h-11c-0.552 0-1 0.448-1 1v6c0 0.552 0.448 1 1 1h11v11c0 0.552 0.448 1 1 1h6c0.552 0 1-0.448 1-1v-11h11c0.552 0 1-0.448 1-1v-6c0-0.552-0.448-1-1-1z\"\/>\r\n<\/svg>\n                            <\/div>\n         \t  <div aria-hidden=\"true\" class=\"bde-faq__icon bde-faq__icon--active\">\n                                <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 448 512\"><!-- Font Awesome Free 5.15.1 by @fontawesome - https:\/\/fontawesome.com License - https:\/\/fontawesome.com\/license\/free (Icons: CC BY 4.0, Fonts: SIL OFL 1.1, Code: MIT License) --><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"\/><\/svg>\n                            <\/div>\n                  <\/button>\n      <\/h3>\n      <div role=\"region\" aria-labelledby=\"bde-faq-241-button-3\" id=\"bde-faq-241-3\" class=\"bde-faq__answer\">\n        <div class=\"bde-faq__answer-content\">\n            <div class=\"breakdance-rich-text-styles\"><p class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\">Ihre Ern\u00e4hrung wird w\u00e4hrend der Vorbereitungs- und Entgiftungsphase schrittweise vereinfacht \u2013 dies ist ein wesentlicher Bestandteil der Wirkungsweise des Programms. In der Regenerationsphase werden die Mahlzeiten abwechslungsreicher und n\u00e4hrstoffreicher. Alle Mahlzeiten werden frisch zubereitet, sind medizinisch auf Ihre jeweilige Programmphase abgestimmt und schmecken wirklich k\u00f6stlich. Die meisten europ\u00e4ischen G\u00e4ste sind \u00fcberrascht, wie zufrieden sie sich f\u00fchlen.<\/p>\n<p class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\">\u00a0<\/p><\/div>\n\n                    <\/div>\n      <\/div>\n    <\/div>\n      <div class=\"bde-faq__item\">\n      <h3 class=\"bde-faq__title-tag\">\n       <button id=\"bde-faq-241-button-4\" aria-expanded=\"false\" aria-controls=\"bde-faq-241-4\" class=\"bde-faq__question js-faq-item\">\n          <span class=\"bde-faq__title\">Kann ich an dem Entgiftungsaufenthalt teilnehmen, wenn ich verschreibungspflichtige Medikamente einnehme?<\/span>\n                           <div aria-hidden=\"true\" class=\"bde-faq__icon bde-faq__icon--inactive\">\n                                <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 32 32\">\r\n<path d=\"M31 12h-11v-11c0-0.552-0.448-1-1-1h-6c-0.552 0-1 0.448-1 1v11h-11c-0.552 0-1 0.448-1 1v6c0 0.552 0.448 1 1 1h11v11c0 0.552 0.448 1 1 1h6c0.552 0 1-0.448 1-1v-11h11c0.552 0 1-0.448 1-1v-6c0-0.552-0.448-1-1-1z\"\/>\r\n<\/svg>\n                            <\/div>\n         \t  <div aria-hidden=\"true\" class=\"bde-faq__icon bde-faq__icon--active\">\n                                <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 448 512\"><!-- Font Awesome Free 5.15.1 by @fontawesome - https:\/\/fontawesome.com License - https:\/\/fontawesome.com\/license\/free (Icons: CC BY 4.0, Fonts: SIL OFL 1.1, Code: MIT License) --><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"\/><\/svg>\n                            <\/div>\n                  <\/button>\n      <\/h3>\n      <div role=\"region\" aria-labelledby=\"bde-faq-241-button-4\" id=\"bde-faq-241-4\" class=\"bde-faq__answer\">\n        <div class=\"bde-faq__answer-content\">\n            <div class=\"breakdance-rich-text-styles\"><p class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\">Ja, unter angemessener \u00e4rztlicher Aufsicht. Unsere \u00c4rzte werden im Rahmen der Erstuntersuchung Ihre derzeitigen Medikamente \u00fcberpr\u00fcfen und Ihr Programm entsprechend zusammenstellen. Bei einigen Medikamenten muss m\u00f6glicherweise vor Ihrer Ankunft mit Ihrem verschreibenden Arzt in Europa R\u00fccksprache gehalten werden. Genau aus diesem Grund bieten wir eine kostenlose medizinische Beratung vor Ihrer Ankunft an \u2013 um solche Aspekte bereits vor Ihrer Buchung zu kl\u00e4ren.<\/p>\n<p class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\">\u00a0<\/p><\/div>\n\n                    <\/div>\n      <\/div>\n    <\/div>\n      <div class=\"bde-faq__item\">\n      <h3 class=\"bde-faq__title-tag\">\n       <button id=\"bde-faq-241-button-5\" aria-expanded=\"false\" aria-controls=\"bde-faq-241-5\" class=\"bde-faq__question js-faq-item\">\n          <span class=\"bde-faq__title\">Ich habe noch nie Ayurveda ausprobiert. Ist das f\u00fcr Anf\u00e4nger geeignet?<br><\/span>\n                           <div aria-hidden=\"true\" class=\"bde-faq__icon bde-faq__icon--inactive\">\n                                <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 32 32\">\r\n<path d=\"M31 12h-11v-11c0-0.552-0.448-1-1-1h-6c-0.552 0-1 0.448-1 1v11h-11c-0.552 0-1 0.448-1 1v6c0 0.552 0.448 1 1 1h11v11c0 0.552 0.448 1 1 1h6c0.552 0 1-0.448 1-1v-11h11c0.552 0 1-0.448 1-1v-6c0-0.552-0.448-1-1-1z\"\/>\r\n<\/svg>\n                            <\/div>\n         \t  <div aria-hidden=\"true\" class=\"bde-faq__icon bde-faq__icon--active\">\n                                <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 448 512\"><!-- Font Awesome Free 5.15.1 by @fontawesome - https:\/\/fontawesome.com License - https:\/\/fontawesome.com\/license\/free (Icons: CC BY 4.0, Fonts: SIL OFL 1.1, Code: MIT License) --><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"\/><\/svg>\n                            <\/div>\n                  <\/button>\n      <\/h3>\n      <div role=\"region\" aria-labelledby=\"bde-faq-241-button-5\" id=\"bde-faq-241-5\" class=\"bde-faq__answer\">\n        <div class=\"bde-faq__answer-content\">\n            <div class=\"breakdance-rich-text-styles\"><p>Auf jeden Fall. Die meisten unserer europ\u00e4ischen G\u00e4ste kommen ohne Vorkenntnisse \u00fcber Ayurveda zu uns. Unsere \u00c4rzte erkl\u00e4ren jede Behandlung, ihren klinischen Zweck und was Sie erwartet \u2013 in einer verst\u00e4ndlichen Sprache, ohne Fachjargon. Sie werden nicht nur ges\u00fcnder abreisen, sondern auch ein echtes Verst\u00e4ndnis f\u00fcr Ihren eigenen K\u00f6rper mitnehmen, das die meisten unserer G\u00e4ste als eines der wertvollsten Dinge bezeichnen, die sie mit nach Hause nehmen.<\/p><\/div>\n\n                    <\/div>\n      <\/div>\n    <\/div>\n      <div class=\"bde-faq__item\">\n      <h3 class=\"bde-faq__title-tag\">\n       <button id=\"bde-faq-241-button-6\" aria-expanded=\"false\" aria-controls=\"bde-faq-241-6\" class=\"bde-faq__question js-faq-item\">\n          <span class=\"bde-faq__title\">Ist der Entgiftungsurlaub in Indien f\u00fcr Europ\u00e4er f\u00fcr Paare geeignet, die gemeinsam reisen?<\/span>\n                           <div aria-hidden=\"true\" class=\"bde-faq__icon bde-faq__icon--inactive\">\n                                <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 32 32\">\r\n<path d=\"M31 12h-11v-11c0-0.552-0.448-1-1-1h-6c-0.552 0-1 0.448-1 1v11h-11c-0.552 0-1 0.448-1 1v6c0 0.552 0.448 1 1 1h11v11c0 0.552 0.448 1 1 1h6c0.552 0 1-0.448 1-1v-11h11c0.552 0 1-0.448 1-1v-6c0-0.552-0.448-1-1-1z\"\/>\r\n<\/svg>\n                            <\/div>\n         \t  <div aria-hidden=\"true\" class=\"bde-faq__icon bde-faq__icon--active\">\n                                <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 448 512\"><!-- Font Awesome Free 5.15.1 by @fontawesome - https:\/\/fontawesome.com License - https:\/\/fontawesome.com\/license\/free (Icons: CC BY 4.0, Fonts: SIL OFL 1.1, Code: MIT License) --><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"\/><\/svg>\n                            <\/div>\n                  <\/button>\n      <\/h3>\n      <div role=\"region\" aria-labelledby=\"bde-faq-241-button-6\" id=\"bde-faq-241-6\" class=\"bde-faq__answer\">\n        <div class=\"bde-faq__answer-content\">\n            <div class=\"breakdance-rich-text-styles\"><p class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\">Ja. Viele europ\u00e4ische Paare besuchen das Tigris-Tal gemeinsam. Jede Person erh\u00e4lt eine v\u00f6llig unabh\u00e4ngige diagnostische Beurteilung und ein individuelles Programm \u2013 je nach Ihrer individuellen Konstitution und Ihren gesundheitlichen Bed\u00fcrfnissen k\u00f6nnen Sie unterschiedliche Behandlungen absolvieren. Dank gemeinsamer Unterk\u00fcnfte, Yoga-Stunden f\u00fcr Paare und gemeinsamer Mahlzeiten ist das Erlebnis sowohl medizinisch individuell zugeschnitten als auch von einer herzlichen Gemeinschaft gepr\u00e4gt.<\/p><\/div>\n\n                    <\/div>\n      <\/div>\n    <\/div>\n  \n<\/div><\/div>\n<\/section><section class=\"bde-section-11336-243 bde-section\">\n  \n  \n\t\n\n\n\n<div class=\"section-container\"><h2 class=\"bde-heading-11336-244 bde-heading\" data-entrance=\"slideUp\">\nBeginnen Sie Ihre Heilungsreise heute\n<\/h2><div id=\"form\" class=\"bde-div-11336-245 bde-div\">\n  \n  \n\t\n\n\n\n<div class=\"bde-div-11336-247 bde-div\">\n  \n  \n\t\n\n\n\n<div class=\"bde-div-11336-248 bde-div\">\n  \n  \n\t\n\n\n\n<div class=\"de-ff-11336-249 de-ff\"><div class='fluentform ff-default fluentform_wrapper_3 ffs_default_wrap'><form data-form_id=\"3\" id=\"fluentform_3\" class=\"frm-fluent-form fluent_form_3 ff-el-form-top ff_form_instance_3_1 ff-form-loading ffs_default\" data-form_instance=\"ff_form_instance_3_1\" method=\"POST\" action=\"\" ><fieldset  style=\"border: none!important;margin: 0!important;padding: 0!important;background-color: transparent!important;box-shadow: none!important;outline: none!important; min-inline-size: 100%;\">\n                    <legend class=\"ff_screen_reader_title\" style=\"display: block; margin: 0!important;padding: 0!important;height: 0!important;text-indent: -999999px;width: 0!important;overflow:hidden;\">Home Kontakt-Formular<\/legend><input type='hidden' name='__fluent_form_embded_post_id' value='11336' \/><input type=\"hidden\" id=\"_fluentform_3_fluentformnonce\" name=\"_fluentform_3_fluentformnonce\" value=\"be72d402a8\" \/><input type=\"hidden\" name=\"_wp_http_referer\" value=\"\/de\/wp-json\/wp\/v2\/pages\/11336\" \/><div data-name=\"ff_cn_id_1\"  class='ff-t-container ff-column-container ff_columns_total_2'><div class='ff-t-cell ff-t-column-1' style='flex-basis: 50%;'><div class='ff-el-group ff-el-form-hide_label'><div class=\"ff-el-input--label ff-el-is-required asterisk-right\"><label for='ff_3_input_text' id='label_ff_3_input_text' aria-label=\"Vollst\u00e4ndiger Name\">Vollst\u00e4ndiger Name<\/label><\/div><div class='ff-el-input--content'><input type=\"text\" name=\"input_text\" class=\"ff-el-form-control\" placeholder=\"Vollst\u00e4ndiger Name\" data-name=\"input_text\" id=\"ff_3_input_text\"  aria-invalid=\"false\" aria-required=\"true\"><\/div><\/div><\/div><div class='ff-t-cell ff-t-column-2' style='flex-basis: 50%;'><div class='ff-el-group ff-el-form-hide_label'><div class=\"ff-el-input--label ff-el-is-required asterisk-right\"><label for='ff_3_phone' id='label_ff_3_phone' aria-label=\"Handy-\/WhatsApp-Nummer\">Handy-\/WhatsApp-Nummer<\/label><\/div><div class='ff-el-input--content'><input name=\"phone\" class=\"ff-el-form-control ff-el-phone\" type=\"tel\" placeholder=\"Handy-\/WhatsApp-Nummer\" data-name=\"phone\" id=\"ff_3_phone\" inputmode=\"tel\"  aria-invalid='false' aria-required=\"true\"><\/div><\/div><\/div><\/div><div data-name=\"ff_cn_id_2\"  class='ff-t-container ff-column-container ff_columns_total_2'><div class='ff-t-cell ff-t-column-1' style='flex-basis: 50%;'><div class='ff-el-group ff-el-form-hide_label'><div class=\"ff-el-input--label ff-el-is-required asterisk-right\"><label for='ff_3_email' id='label_ff_3_email' aria-label=\"E-Mail Adresse\">E-Mail Adresse<\/label><\/div><div class='ff-el-input--content'><input type=\"email\" name=\"email\" id=\"ff_3_email\" class=\"ff-el-form-control\" placeholder=\"E-Mail Adresse\" data-name=\"email\"  aria-invalid=\"false\" aria-required=\"true\"><\/div><\/div><\/div><div class='ff-t-cell ff-t-column-2' style='flex-basis: 50%;'><div class='ff-el-group ff-el-form-hide_label'><div class=\"ff-el-input--label ff-el-is-required asterisk-right\"><label for='ff_3_input_text_1' id='label_ff_3_input_text_1' aria-label=\"Land \/ Stadt\">Land \/ Stadt<\/label><\/div><div class='ff-el-input--content'><input type=\"text\" name=\"input_text_1\" class=\"ff-el-form-control\" placeholder=\"Land \/ Stadt\" data-name=\"input_text_1\" id=\"ff_3_input_text_1\"  aria-invalid=\"false\" aria-required=\"true\"><\/div><\/div><\/div><\/div><div data-name=\"ff_cn_id_3\"  class='ff-t-container ff-column-container ff_columns_total_2'><div class='ff-t-cell ff-t-column-1' style='flex-basis: 50%;'><div class='ff-el-group ff-el-form-hide_label'><div class=\"ff-el-input--label ff-el-is-required asterisk-right\"><label for='ff_3_dropdown' id='label_ff_3_dropdown' aria-label=\"Prim\u00e4res Gesundheitsproblem\">Prim\u00e4res Gesundheitsproblem<\/label><\/div><div class='ff-el-input--content'><select name=\"dropdown\" id=\"ff_3_dropdown\" class=\"ff-el-form-control\" data-name=\"dropdown\" data-calc_value=\"0\"  aria-invalid=\"false\" aria-required=\"true\" aria-labelledby=\"label_ff_3_dropdown\"><option value=\"\">Prim\u00e4res Gesundheitsproblem<\/option><option value=\"Primary Health Concern\"  >Prim\u00e4res Gesundheitsproblem<\/option><option value=\"Rejuvenation &amp;amp; Relaxation (No Medical Condition)\"  >Verj\u00fcngung und Entspannung (keine medizinische Voraussetzung)<\/option><option value=\"Paralysis \/ Neuro Rehabilitation\"  >L\u00e4hmungen \/ Neuro-Rehabilitation<\/option><option value=\"Stroke Recovery\"  >Erholung nach Schlaganfall<\/option><option value=\"Spine &amp;amp; Disc Problems\"  >Wirbels\u00e4ule und Bandscheibenprobleme<\/option><option value=\"Chronic Back \/ Neck Pain\"  >Chronische R\u00fccken-\/Nackenschmerzen<\/option><option value=\"Arthritis \/ Joint Pain\"  >Arthritis \/ Gelenkschmerzen<\/option><option value=\"Post-Surgery Rehabilitation\"  >Postoperative Rehabilitation<\/option><option value=\"Sports Injury Recovery\"  >Genesung bei Sportverletzungen<\/option><option value=\"Diabetes Management\"  >Diabetes-Management<\/option><option value=\"Blood Pressure \/ Heart Health\"  >Blutdruck \/ Herzgesundheit<\/option><option value=\"Hormonal Imbalance (PCOS, Thyroid, etc.)\"  >Hormonelles Ungleichgewicht (PCOS, Schilddr\u00fcse, etc.)<\/option><option value=\"Digestive Disorders (IBS, Acidity, Fatty Liver, etc.)\"  >Verdauungsst\u00f6rungen (IBS, \u00dcbers\u00e4uerung, Fettleber, etc.)<\/option><option value=\"Kidney \/ Liver Disorders\"  >Nieren-\/Leber-Erkrankungen<\/option><option value=\"Auto-Immune Conditions\"  >Autoimmunerkrankungen<\/option><option value=\"Respiratory Issues (Asthma, Sinus, Allergy)\"  >Atemwegserkrankungen (Asthma, Sinus, Allergie)<\/option><option value=\"Skin Disorders (Psoriasis, Eczema, Acne, etc.)\"  >Hautkrankheiten (Schuppenflechte, Ekzeme, Akne usw.)<\/option><option value=\"Mental Wellness (Stress, Anxiety, Sleep Issues)\"  >Psychisches Wohlbefinden (Stress, Angstzust\u00e4nde, Schlafprobleme)<\/option><option value=\"Detox &amp;amp; Panchakarma\"  >Entgiftung und Panchakarma<\/option><option value=\"Weight Loss &amp;amp; Metabolic Health\"  >Gewichtsabnahme und metabolische Gesundheit<\/option><option value=\"General Wellness &amp;amp; Preventive Care\"  >Allgemeines Wohlbefinden und Pr\u00e4ventivmedizin<\/option><option value=\"Other&amp;nbsp;Health&amp;nbsp;Issue\"  >Andere Gesundheitsprobleme<\/option><\/select><\/div><\/div><\/div><div class='ff-t-cell ff-t-column-2' style='flex-basis: 50%;'><div class='ff-el-group ff-el-form-hide_label'><div class=\"ff-el-input--label ff-el-is-required asterisk-right\"><label for='ff_3_dropdown_1' id='label_ff_3_dropdown_1' aria-label=\"Bevorzugte Kontaktmethode\">Bevorzugte Kontaktmethode<\/label><\/div><div class='ff-el-input--content'><select name=\"dropdown_1\" id=\"ff_3_dropdown_1\" class=\"ff-el-form-control\" data-name=\"dropdown_1\" data-calc_value=\"0\"  aria-invalid=\"false\" aria-required=\"true\" aria-labelledby=\"label_ff_3_dropdown_1\"><option value=\"\">Bevorzugte Kontaktmethode<\/option><option value=\"Call\"  >Rufen Sie  an.<\/option><option value=\"WhatsApp\"  >WhatsApp<\/option><option value=\"Email\"  >E-Mail<\/option><\/select><\/div><\/div><\/div><\/div><div class='ff-el-group' ><div class='ff-el-input--content'><div data-fluent_id='3' name='g-recaptcha-response'><div\n\t\tdata-sitekey='6LdLRYAsAAAAAC0uuZGVijHNMamUNyYMF1AjHQku'\n\t\tid='fluentform-recaptcha-3-1'\n\t\tclass='ff-el-recaptcha g-recaptcha'\n\t\tdata-callback='fluentFormrecaptchaSuccessCallback'><\/div><\/div><\/div><\/div><div class='ff-el-group ff-text-left ff_submit_btn_wrapper'><button type=\"submit\" class=\"ff-btn ff-btn-submit ff-btn-md ff_btn_style\"  aria-label=\"Einreichen\">Einreichen<\/button><\/div><\/fieldset><input type=\"hidden\" name=\"trp-form-language\" value=\"de\"\/><\/form><div id='fluentform_3_errors' class='ff-errors-in-stack ff_form_instance_3_1 ff-form-loading_errors ff_form_instance_3_1_errors'><\/div><\/div>            <script type=\"text\/javascript\">\n                window.fluent_form_ff_form_instance_3_1 = {\"id\":\"3\",\"settings\":{\"layout\":{\"labelPlacement\":\"top\",\"asteriskPlacement\":\"asterisk-right\",\"helpMessagePlacement\":\"with_label\",\"errorMessagePlacement\":\"inline\",\"cssClassName\":\"\"},\"restrictions\":{\"denyEmptySubmission\":{\"enabled\":false}}},\"form_instance\":\"ff_form_instance_3_1\",\"form_id_selector\":\"fluentform_3\",\"rules\":{\"input_text\":{\"required\":{\"value\":true,\"message\":\"Dieses Feld ist erforderlich\",\"global_message\":\"This field is required\",\"global\":true}},\"phone\":{\"required\":{\"value\":true,\"global\":true,\"message\":\"Dieses Feld ist erforderlich\",\"global_message\":\"This field is required\"},\"valid_phone_number\":{\"value\":false,\"global\":true,\"message\":\"Telefonnummer ist ung\\u00fcltig\",\"global_message\":\"Phone number is not valid\"}},\"email\":{\"required\":{\"value\":true,\"message\":\"Dieses Feld ist erforderlich\",\"global_message\":\"This field is required\",\"global\":true},\"email\":{\"value\":true,\"message\":\"Dieses Feld muss eine g\\u00fcltige E-Mail-Adresse enthalten\",\"global_message\":\"This field must contain a valid email\",\"global\":true}},\"input_text_1\":{\"required\":{\"value\":true,\"message\":\"Dieses Feld ist erforderlich\",\"global_message\":\"This field is required\",\"global\":true}},\"dropdown\":{\"required\":{\"value\":true,\"message\":\"Dieses Feld ist erforderlich\",\"global_message\":\"This field is required\",\"global\":true}},\"dropdown_1\":{\"required\":{\"value\":true,\"message\":\"Dieses Feld ist erforderlich\",\"global_message\":\"This field is required\",\"global\":true}},\"g-recaptcha-response\":[]},\"debounce_time\":300};\n                            <\/script>\n            \r\n<\/div>\n<\/div>\n<\/div>\n<\/div><\/div>\n<\/section>","protected":false},"excerpt":{"rendered":"<p>Das Detox-Retreat in Indien f\u00fcr Europ\u00e4er, das tiefer geht als eine Saftkur \u2013 Sie haben es schon mit \u201eClean Eating\u201c versucht. Sie haben die Wochenend-Entgiftung gemacht. Sie haben auf Alkohol, Gluten und Zucker verzichtet. Und doch f\u00fchlt sich im Inneren immer noch etwas schwer, tr\u00e4ge und ungel\u00f6st an. Das liegt daran, dass die meisten Entgiftungsprogramme nur an der Oberfl\u00e4che kratzen \u2013 und Ihr K\u00f6rper Giftstoffe speichert [\u2026]<\/p>","protected":false},"author":4,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_breakdance_hide_in_design_set":false,"_breakdance_tags":"","iawp_total_views":1,"footnotes":""},"class_list":["post-11336","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/tigrisvalley.com\/de\/wp-json\/wp\/v2\/pages\/11336","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tigrisvalley.com\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/tigrisvalley.com\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/tigrisvalley.com\/de\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/tigrisvalley.com\/de\/wp-json\/wp\/v2\/comments?post=11336"}],"version-history":[{"count":2,"href":"https:\/\/tigrisvalley.com\/de\/wp-json\/wp\/v2\/pages\/11336\/revisions"}],"predecessor-version":[{"id":11338,"href":"https:\/\/tigrisvalley.com\/de\/wp-json\/wp\/v2\/pages\/11336\/revisions\/11338"}],"wp:attachment":[{"href":"https:\/\/tigrisvalley.com\/de\/wp-json\/wp\/v2\/media?parent=11336"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}